{"id":5,"count":71,"description":"","link":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/","name":"PUBG Mobile","slug":"pubg-mobile","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PUBG Mobile Archives - UniPin Blog EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.unipin.com\/en\/pubg-mobile\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PUBG Mobile Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.unipin.com\/en\/pubg-mobile\/\" \/>\n<meta property=\"og:site_name\" content=\"UniPin Blog EN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@unipinindonesia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/pubg-mobile\\\/\",\"url\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/pubg-mobile\\\/\",\"name\":\"PUBG Mobile Archives - UniPin Blog EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/pubg-mobile\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/pubg-mobile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PUBG Mobile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/\",\"name\":\"UniPin Blog EN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#organization\",\"name\":\"UniPin\",\"url\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/UniPin-Logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/UniPin-Logo.png\",\"width\":1958,\"height\":1125,\"caption\":\"UniPin\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.unipin.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniPin\",\"https:\\\/\\\/x.com\\\/unipinindonesia\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClINXntvfPr_44coZpObmDA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PUBG Mobile Archives - UniPin Blog EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/","og_locale":"en_US","og_type":"article","og_title":"PUBG Mobile Archives","og_url":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/","og_site_name":"UniPin Blog EN","twitter_card":"summary_large_image","twitter_site":"@unipinindonesia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/","url":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/","name":"PUBG Mobile Archives - UniPin Blog EN","isPartOf":{"@id":"https:\/\/blog.unipin.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.unipin.com\/en\/pubg-mobile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.unipin.com\/en\/"},{"@type":"ListItem","position":2,"name":"PUBG Mobile"}]},{"@type":"WebSite","@id":"https:\/\/blog.unipin.com\/en\/#website","url":"https:\/\/blog.unipin.com\/en\/","name":"UniPin Blog EN","description":"","publisher":{"@id":"https:\/\/blog.unipin.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.unipin.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.unipin.com\/en\/#organization","name":"UniPin","url":"https:\/\/blog.unipin.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.unipin.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blog.unipin.com\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/UniPin-Logo.png","contentUrl":"https:\/\/blog.unipin.com\/en\/wp-content\/uploads\/sites\/2\/2021\/10\/UniPin-Logo.png","width":1958,"height":1125,"caption":"UniPin"},"image":{"@id":"https:\/\/blog.unipin.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniPin","https:\/\/x.com\/unipinindonesia","https:\/\/www.youtube.com\/channel\/UClINXntvfPr_44coZpObmDA"]}]}},"_links":{"self":[{"href":"https:\/\/blog.unipin.com\/en\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.unipin.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.unipin.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.unipin.com\/en\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}